{"id":25346,"date":"2017-03-22T11:32:09","date_gmt":"2017-03-22T11:32:09","guid":{"rendered":"http:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3.jpg"},"modified":"2017-03-22T11:32:09","modified_gmt":"2017-03-22T11:32:09","slug":"profondo-rosso-3","status":"inherit","type":"attachment","link":"https:\/\/leitmovie.it\/en_gb\/profondo-rosso\/profondo-rosso-3","title":{"rendered":"Profondo rosso 3"},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-300x169.jpg 300w, https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-615x346.jpg 615w, https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-400x225.jpg 400w, https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-292x164.jpg 292w, https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":720,"height":405,"file":"2017\/03\/Profondo-rosso-3.jpg","sizes":{"thumbnail":{"file":"Profondo-rosso-3-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-150x150.jpg"},"medium":{"file":"Profondo-rosso-3-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-300x169.jpg"},"posts-widget-thumb":{"file":"Profondo-rosso-3-60x60.jpg","width":60,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-60x60.jpg"},"posts-widget-thumb-small":{"file":"Profondo-rosso-3-43x43.jpg","width":43,"height":43,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-43x43.jpg"},"wpv-sermons-thumbnail":{"file":"Profondo-rosso-3-106x106.jpg","width":106,"height":106,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-106x106.jpg"},"post-loop":{"file":"Profondo-rosso-3-480x369.jpg","width":480,"height":369,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-480x369.jpg"},"portfolio-masonry-2":{"file":"Profondo-rosso-3-615x346.jpg","width":615,"height":346,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-615x346.jpg"},"portfolio-loop-2":{"file":"Profondo-rosso-3-615x405.jpg","width":615,"height":405,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-615x405.jpg"},"post-small-2":{"file":"Profondo-rosso-3-615x405.jpg","width":615,"height":405,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-615x405.jpg"},"portfolio-masonry-3":{"file":"Profondo-rosso-3-400x225.jpg","width":400,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-400x225.jpg"},"portfolio-loop-3":{"file":"Profondo-rosso-3-400x266.jpg","width":400,"height":266,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-400x266.jpg"},"post-small-3":{"file":"Profondo-rosso-3-400x307.jpg","width":400,"height":307,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-400x307.jpg"},"portfolio-masonry-4":{"file":"Profondo-rosso-3-292x164.jpg","width":292,"height":164,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-292x164.jpg"},"portfolio-loop-4":{"file":"Profondo-rosso-3-292x195.jpg","width":292,"height":195,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-292x195.jpg"},"post-small-4":{"file":"Profondo-rosso-3-292x225.jpg","width":292,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3-292x225.jpg"},"full":{"file":"Profondo-rosso-3.jpg","width":720,"height":405,"mime_type":"image\/jpeg","source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":25343,"source_url":"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/03\/Profondo-rosso-3.jpg","_links":{"self":[{"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/media\/25346"}],"collection":[{"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/comments?post=25346"}]}}