{"id":24056,"date":"2018-01-27T06:28:58","date_gmt":"2018-01-27T06:28:58","guid":{"rendered":"http:\/\/leitmovie.it\/?p=24056"},"modified":"2018-01-27T09:01:38","modified_gmt":"2018-01-27T09:01:38","slug":"springsteen-i","status":"publish","type":"post","link":"https:\/\/leitmovie.it\/en_gb\/springsteen-i","title":{"rendered":"[:it]Springsteen &#038; I[:]"},"content":{"rendered":"<p>[:it]<\/p>\n<hr \/>\n<h5 style=\"text-align: justify;\">In onda domenica 28 gennaio su RAI 5, ore 01.30<\/h5>\n<div class=\"author-post-rating\"><span class=\"author-post-rating-label\">Voto al film:<\/span> <span class=\"author-post-rating-stars\" title=\"3 out of 5 stars\"><img decoding=\"async\" src=\"https:\/\/leitmovie.it\/wp-content\/plugins\/author-post-ratings\/images\/star-active.png\" \/><img decoding=\"async\" src=\"https:\/\/leitmovie.it\/wp-content\/plugins\/author-post-ratings\/images\/star-active.png\" \/><img decoding=\"async\" src=\"https:\/\/leitmovie.it\/wp-content\/plugins\/author-post-ratings\/images\/star-active.png\" \/><img decoding=\"async\" src=\"https:\/\/leitmovie.it\/wp-content\/plugins\/author-post-ratings\/images\/star-inactive.png\" \/><img decoding=\"async\" src=\"https:\/\/leitmovie.it\/wp-content\/plugins\/author-post-ratings\/images\/star-inactive.png\" \/><\/span>\n<\/div><!-- .author-post-rating -->\n<h4 style=\"text-align: justify;\"><strong>Fenomenologia springsteeniana<\/strong><\/h4>\n<p style=\"text-align: justify;\">Con oltre quarant\u2019anni di attivit\u00e0 alle spalle, Bruce Springsteen resta tutt\u2019oggi uno dei casi mediatici pi\u00f9 significativi della cultura popolare del Novecento. Figura emblematica dell\u2019America \u201caltra\u201d di cui da sempre si \u00e8 fatto cantore, il rocker di Freehold ha conquistato negli anni il pubblico di tutto il mondo, un numero sempre crescente di fan che regolarmente attendono fiduciosi la chiamata a raccolta del loro autore preferito in occasione di concerti o altri eventi che lo vedono protagonista.<!--more--><\/p>\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-24058\" src=\"http:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-2-300x200.jpg\" alt=\"Bruce Springsteen_Springsteen &amp; I (2)\" width=\"300\" height=\"200\" srcset=\"https:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-2-300x200.jpg 300w, https:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-2-768x512.jpg 768w, https:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-2-1024x683.jpg 1024w, https:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-2-600x400.jpg 600w, https:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-2-1260x840.jpg 1260w, https:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-2-615x410.jpg 615w, https:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-2-400x266.jpg 400w, https:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-2-292x195.jpg 292w, https:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-2.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Ma il particolare legame creatosi tra il musicista e il suo pubblico non \u00e8 solo un processo di reciproca esaltazione che viene a fare del primo un carismatico idolo, va oltre, radicandosi nell\u2019esistenza dei suoi ammiratori, in un processo di identificazione che per molti rende Bruce una sorta di fratello maggiore, sempre disposto a consigliare e confortare dalle asperit\u00e0 della vita.<\/p>\n<p style=\"text-align: justify;\"><em>Springsteen &amp; I<\/em>, \u00e8 un lavoro onesto e sincero che d\u00e0 la parola per la prima volta non all\u2019artista, ma ai fan, offrendo ad alcuni di loro la possibilit\u00e0 di esprimere in pochi minuti ci\u00f2 che Bruce significa per essi, il suo ruolo nelle rispettive vite, l\u2019affetto che li lega al proprio mito. Un atto dovuto verso chi permette a Bruce Springsteen di essere Bruce Springsteen.<\/p>\n<p style=\"text-align: justify;\">Quelle selezionate dal regista Baillie Walsh sono testimonianze toccanti perch\u00e9 sincere, veri atti d\u2019amore verso un personaggio la cui arte \u00e8 stata ed \u00e8 ancora capace di farsi universale, superando limiti geografici, di et\u00e0, estrazione sociale e razza. <img decoding=\"async\" class=\"size-medium wp-image-24059 alignright\" src=\"http:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-300x191.jpg\" alt=\"Bruce Springsteen_Springsteen &amp; I\" width=\"300\" height=\"191\" srcset=\"https:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-300x191.jpg 300w, https:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-400x254.jpg 400w, https:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I-292x186.jpg 292w, https:\/\/leitmovie.it\/wp-content\/uploads\/2016\/08\/Bruce-Springsteen_Springsteen-I.jpg 450w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Ogni ammiratore ha un ricordo personale e allo stesso tempo collettivo dell\u2019artista, un ideale rapporto confidenziale intessuto con lui per ragioni e in situazioni disparate.<\/p>\n<p style=\"text-align: justify;\">\u00c8 facile per un non springsteeniano ridurre il documentario a una sorta di grande video celebrativo in stile YouTube, con filmati da concerti o amatoriali ai quali sono affiancate le testimonianze dei fan registrate in clip di qualit\u00e0 e formati vari, dove la \u201cbrutta\u201d immagine \u00e8 supplita dall\u2019unicit\u00e0 del contenuto. Ma pur non sottraendosi all\u2019inevitabile venerazione di Bruce, la pellicola va oltre, facendo degli ammiratori presi a campione espressioni significative di un caso sociologico che difficilmente pu\u00f2 essere spiegato; un fenomeno che per essere compreso va semplicemnte vissuto, con l\u2019apertura e la disposizione d\u2019animo di un <em>blood brother<\/em>.<\/p>\n<h5 style=\"text-align: justify;\"><\/h5>\n<h5 style=\"text-align: justify;\"><strong>SCHEDA TECNICA<\/strong><br \/>\n<strong>Springsteen &amp; I (Id., USA, 2013) \u2013 REGIA: Baillie Walsh. FOTOGRAFIA: Marco Tomaselli. MONTAGGIO: Ben Harrex. MUSICHE: Bruce Springsteen. CAST: Bruce Springsteen, Mitchell A. S. Hallock, Koichi Murakami. GENERE: Documentario. DURATA: 77\u2032.<\/strong><\/h5>\n<p><iframe title=\"SPRINGSTEEN &amp; I (Official Trailer) - Coming this July\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/HVQUeCi9V0s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>[:it] In onda domenica 28 gennaio su RAI 5, ore 01.30 Fenomenologia springsteeniana Con oltre quarant\u2019anni di attivit\u00e0 alle spalle, Bruce Springsteen resta tutt\u2019oggi uno dei casi mediatici pi\u00f9 significativi [&hellip;]<\/p>","protected":false},"author":6,"featured_media":24057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[97],"tags":[8,140,101],"_links":{"self":[{"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/posts\/24056"}],"collection":[{"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/comments?post=24056"}],"version-history":[{"count":0,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/posts\/24056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/media\/24057"}],"wp:attachment":[{"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/media?parent=24056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/categories?post=24056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/tags?post=24056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}