{"id":26146,"date":"2017-10-28T06:08:16","date_gmt":"2017-10-28T06:08:16","guid":{"rendered":"http:\/\/leitmovie.it\/?p=26146"},"modified":"2017-10-28T08:10:49","modified_gmt":"2017-10-28T08:10:49","slug":"hello-again","status":"publish","type":"post","link":"https:\/\/leitmovie.it\/en_gb\/hello-again","title":{"rendered":"[:it]Gender Bender 2017 &#8211; Hello Again[:en]Lovers Film Festival 2017 &#8211; Hello Again[:]"},"content":{"rendered":"<p>[:it]<\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><div class=\"author-post-rating\"><span class=\"author-post-rating-label\">Voto al film:<\/span> <span class=\"author-post-rating-stars\" title=\"3 out of 5 stars\"><img decoding=\"async\" src=\"https:\/\/leitmovie.it\/wp-content\/plugins\/author-post-ratings\/images\/star-active.png\" \/><img decoding=\"async\" src=\"https:\/\/leitmovie.it\/wp-content\/plugins\/author-post-ratings\/images\/star-active.png\" \/><img decoding=\"async\" src=\"https:\/\/leitmovie.it\/wp-content\/plugins\/author-post-ratings\/images\/star-active.png\" \/><img decoding=\"async\" src=\"https:\/\/leitmovie.it\/wp-content\/plugins\/author-post-ratings\/images\/star-inactive.png\" \/><img decoding=\"async\" src=\"https:\/\/leitmovie.it\/wp-content\/plugins\/author-post-ratings\/images\/star-inactive.png\" \/><\/span>\n<\/div><!-- .author-post-rating --><\/p>\n<h4 style=\"text-align: justify;\"><strong><em>Girotondo<\/em> senza tempo<\/strong><\/h4>\n<p style=\"text-align: justify;\">Presentato in chiusura del 32\u00b0 Lovers Film Festival di Torino e poi passato al Gender Bender Festival, <em>Hello Again<\/em> di Tom Gustafson \u00e8 la trasposizione cinematografica dell&#8217;omonimo musical di Michael John LaChiusa portato in scena sui palchi off-Broadway all&#8217;inizio degli anni novanta.<\/p>\n<p style=\"text-align: justify;\"><!--more--><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-26148\" src=\"http:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/hello-again_1-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/hello-again_1-300x169.jpg 300w, https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/hello-again_1.jpg 400w, https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/hello-again_1-292x164.jpg 292w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Tratto dall&#8217;opera teatrale <em>Girotondo<\/em> di Arthur Schnitzler, <em>Hello Again<\/em> ne conserva la struttura, gran parte dei personaggi e attinge a piene mani ai dialoghi originali, ma al contempo la attualizza in modo fresco ed efficace nella forma e nei contenuti.<\/p>\n<p style=\"text-align: justify;\">L&#8217;opera di Schnitzler si sviluppa attraverso una serie di dieci incontri tra coppie di amanti nella Vienna di fine Ottocento. I dieci protagonisti, caratteri archetipici appena abbozzati nelle poche pagine in cui si manifesta la loro esistenza, sono di varia et\u00e0 ed estrazione sociale: la prostituta, il soldato, la cameriera, il giovane signore, la giovane signora, il marito, la ragazzina, il poeta, l&#8217;attrice e il conte. Ognuno di loro compare in due quadri consecutivi e l&#8217;incontro tra il conte e la prostituta chiude la struttura circolare dell&#8217;opera.<\/p>\n<p style=\"text-align: justify;\">Ogni quadro vede i due personaggi dialogare in uno zoppicante scambio di frasi allusive, tentativi di seduzione talvolta impacciati, talvolta estremamente freddi e calcolati. Nonostante reticenze, circostanze sfavorevoli e qualche incidente di percorso, ogni incontro si conclude con l&#8217;atto sessuale, che in <em>Girotondo<\/em> non viene mai descritto: dopo una breve ellissi ci ricongiungiamo con i due che si congedano.<\/p>\n<p style=\"text-align: justify;\">Ad accomunare tutti, indipendentemente da ceto sociale, professione, et\u00e0 e genere, \u00e8 la ricerca disperata, attraverso l&#8217;atto carnale, di un breve istante di felicit\u00e0, di una tregua dalla percezione nichilista dell&#8217;esistenza, l&#8217;urgenza del carpe diem. \u201cChiss\u00e0 se domani saremo ancora vivi!\u201d, dice la prostituta al soldato che tergiversa. \u201cLa vita \u00e8 cos\u00ec vuota, cos\u00ec futile&#8230; e poi&#8230; cos\u00ec breve&#8230; cos\u00ec orribilmente breve! C&#8217;\u00e8 solo una gioia&#8230; trovare una creatura dalla quale essere amati&#8230;\u201d; qui a parlare \u00e8 il giovane signore. Ma ad accomunarli \u00e8 anche la realizzazione finale che l&#8217;amore e la felicit\u00e0 non hanno niente a che fare con questi incontri meramente fisici: i due si salutano con distacco, pi\u00f9 estranei e soli di prima.<\/p>\n<p style=\"text-align: justify;\"><em>Hello Again<\/em> sostituisce New York a Vienna e rende il <em>fil rouge<\/em> di <em>Girotondo<\/em> ancora pi\u00f9 universale, rompendo l&#8217;unit\u00e0 di tempo e abbattendo i confini di genere e orientamento sessuale: ogni quadro \u00e8 ambientato in un&#8217;epoca diversa del Novecento, la prostituta<em><img decoding=\"async\" class=\"size-medium wp-image-26150 alignright\" src=\"http:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/Hello-Again-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/Hello-Again-300x169.jpg 300w, https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/Hello-Again-615x346.jpg 615w, https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/Hello-Again-400x225.jpg 400w, https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/Hello-Again-292x164.jpg 292w, https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/Hello-Again.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/em> Leocadia \u00e8 interpretata da un uomo, la ragazzina diventa un giovane dalla bellezza efebica (The Young Thing) e il conte una senatrice (una magnetica Martha Plimpton).<\/p>\n<p style=\"text-align: justify;\">Il continuo salto da un decennio all&#8217;altro (senza ordine cronologico) permette di costruire una colonna sonora che spazia tra generi musicali diversissimi tra loro, dallo swing degli anni &#8217;20 che proviene da un locale nell&#8217;episodio del soldato e la cameriera alla musica dance che The Young Thing balla negli anni &#8217;70, dal doo-wop degli anni &#8217;50 al pop commerciale di inizio millennio dell&#8217;attrice-popstar con sintetizzatori, vocoder e con tanto di <a href=\"https:\/\/www.youtube.com\/watch?v=-o4WgOO_6Cg&amp;list=PLXnHWWdpL-Y46jGJrLtWfWWlaQXBzeV_M&amp;index=2\" target=\"_blank\" rel=\"noopener noreferrer\">videoclip<\/a> parodistico dall&#8217;estetica galattico-tribale.<\/p>\n<p style=\"text-align: justify;\">I brani cantati, firmati da LaChiusa e ripresi dal musical teatrale, non sono sempre convincenti e memorabili, ma \u00e8 forse una scelta ragionata, volta a veicolare anche sul piano sonoro quel disagio, quell&#8217;inadeguatezza che connota i protagonisti. Restano impressi il motivo <em>Hello Again<\/em>, cantato dalla prostituta e poi dalle voci di tutti i personaggi nella scena finale, <em>The Greatest of Adventures<\/em>, il malinconico brano intonato dalla giovane signora nella vasca da bagno, e l&#8217;energica performance dell&#8217;infermiera che sottomette il giovane signore.<\/p>\n<p style=\"text-align: justify;\"><em><img decoding=\"async\" class=\"size-medium wp-image-26149 alignleft\" src=\"http:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/hello-again_2-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/hello-again_2-300x169.jpg 300w, https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/hello-again_2.jpg 400w, https:\/\/leitmovie.it\/wp-content\/uploads\/2017\/07\/hello-again_2-292x164.jpg 292w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/em><em>Hello Again<\/em> \u00e8 un musical anomalo, quasi totalmente privo di coreografie, girato perlopi\u00f9 su campi stretti, con una regia che si fa visibile solo in rari momenti, come quando segue con ironia le indicazioni dello scrittore-regista nell&#8217;episodio ambientato negli anni &#8217;70.<\/p>\n<p style=\"text-align: justify;\">\u00c8 sicuramente riuscito l&#8217;esperimento di rappresentare sul grande schermo la vuota, disperata ritualit\u00e0 di <em>Girotondo<\/em>. A differenza di Schnitzler, Gustafson mette in scena, in modo essenziale e senza mai cadere nel voyeurismo, anche l&#8217;atto sessuale (quando avviene, perch\u00e9 in <em>Hello Again<\/em> qualcuno viene respinto), ma \u00e8 cos\u00ec profondo il distacco tra i due amanti prima e dopo, che anche l&#8217;atto stesso \u00e8 percepito come freddo e meccanico, quando non goffo e ridicolo. Un film sull&#8217;eros senza erotismo.<\/p>\n<h5 style=\"text-align: justify;\"><strong>SCHEDA TECNICA<\/strong><br \/>\n<strong>Hello Again (Stati Uniti, 2017) \u2013 REGIA: Tom Gustafson. SCENEGGIATURA: Cory Crueckeberg. MONTAGGIO: Cory Crueckeberg.. MUSICHE: Michael John LaChiusa. CAST: Sam Underwood, Nolan Gerard Funk, Jenna Ushkowitz, Al Calderon. GENERE: Musical. DURATA: 105&#8242;<\/strong><\/h5>\n<p>&nbsp;<\/p>\n<p><iframe title=\"HELLO AGAIN - Official Trailer #1\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/2gm5FF-S64I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>[:it] Girotondo senza tempo Presentato in chiusura del 32\u00b0 Lovers Film Festival di Torino e poi passato al Gender Bender Festival, Hello Again di Tom Gustafson \u00e8 la trasposizione cinematografica [&hellip;]<\/p>","protected":false},"author":22,"featured_media":26147,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139],"tags":[8,213,238],"_links":{"self":[{"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/posts\/26146"}],"collection":[{"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/comments?post=26146"}],"version-history":[{"count":0,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/posts\/26146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/media\/26147"}],"wp:attachment":[{"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/media?parent=26146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/categories?post=26146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leitmovie.it\/en_gb\/wp-json\/wp\/v2\/tags?post=26146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}